{"id":1476,"date":"2017-02-09T14:04:48","date_gmt":"2017-02-09T14:04:48","guid":{"rendered":"http:\/\/consulting.stylemixthemes.com\/demo\/?page_id=1476"},"modified":"2026-05-03T14:36:26","modified_gmt":"2026-05-03T14:36:26","slug":"contact-two","status":"publish","type":"page","link":"https:\/\/instantcredit24.ro\/index.php\/contact-two\/","title":{"rendered":"Contact two"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1476\" class=\"elementor elementor-1476\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65d96c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65d96c0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65d9ba3\" data-id=\"65d9ba3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65d9fb9 elementor-widget elementor-widget-text-editor\" data-id=\"65d9fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-family: Montserrat; color: #444444; font-size: 16px; letter-spacing: -0.4px;\">Please let us know if you have a question, want to leave a comment, or would like further information about Consulting WP.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65da22a elementor-widget elementor-widget-stm_contacts_widget\" data-id=\"65da22a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"stm_contacts_widget.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"stm_contacts_widget consulting_elementor_contacts_widget style_4 \">\n    \n            <h4 class=\"no_stripe\">contact details<\/h4>\n    \n    \n        <ul>\n                            <li>\n                    <div class=\"icon\"><i class=\"fa fa-map-marker\"><\/i><\/div>\n                    <div class=\"text\">1010 Avenue of the Moon\nNew York, NY 10018 US.<\/div>\n                <\/li>\n                                        <li>\n                    <div class=\"icon\"><i class=\"fa fa-phone\"><\/i><\/div>\n                    <div class=\"text\">\n                        +1 628 123 4000                                            <\/div>\n                <\/li>\n                                                    <li>\n                    <div class=\"icon\"><i class=\"fa fa-envelope\"><\/i><\/div>\n                    <div class=\"text\"><a href=\"mailto:&#98;ra&#110;&#100;on&#64;&#99;&#111;&#110;s&#117;ltin&#103;&#46;com\">br&#97;ndo&#110;&#64;&#99;on&#115;&#117;l&#116;i&#110;g.c&#111;m<\/a><\/div>\n                <\/li>\n                                <\/ul>\n                    <ul class=\"socials\">\n                                    <li><a href=\"#\" target=\"_blank\" class=\"social-facebook\"><i class=\"fa fa-facebook\"><\/i><\/a><\/li>\n                                                    <li><a href=\"#\" target=\"_blank\" class=\"social-twitter\"><i class=\"fa fa-twitter\"><\/i><\/a><\/li>\n                                                    <li><a href=\"#\" target=\"_blank\" class=\"social-linkedin\"><i class=\"fa fa-linkedin\"><\/i><\/a><\/li>\n                                                    <li><a href=\"#\" target=\"_blank\" class=\"social-google-plus\"><i class=\"fa fa-google-plus\"><\/i><\/a><\/li>\n                                                    <li><a href=\"skype:#\" class=\"social-skype\"><i class=\"fa fa-skype\"><\/i><\/a><\/li>\n                            <\/ul>\n        \n    \n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65da2e5\" data-id=\"65da2e5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65dab06 elementor-widget elementor-widget-stm_contact_form_7\" data-id=\"65dab06\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"stm_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1472-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1472\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/1476#wpcf7-f1472-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1472\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1472-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"request_callback\">\n    <div class=\"row\">\n        <div class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\">\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"text-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"First name *\" value=\"\" type=\"text\" name=\"text-name\" \/><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"title\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Title\" value=\"\" type=\"text\" name=\"title\" \/><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Company\/Position\" value=\"\" type=\"text\" name=\"company\" \/><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-mail *\" value=\"\" type=\"email\" name=\"email\" \/><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"menu-774\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-774\"><option value=\"\">Reason for Contact *<\/option><option value=\"Value1\">Value1<\/option><option value=\"Value2\">Value2<\/option><\/select><\/span>\n            <\/div>\n        <\/div>\n        <div class=\"col-lg-6 col-md-6 col-sm-6 col-xs-12\">\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"menu-363\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"menu-363\"><option value=\"\">Area of Interest *<\/option><option value=\"Value1\">Value1<\/option><option value=\"Value2\">Value2<\/option><\/select><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Subject *\" value=\"\" type=\"text\" name=\"subject\" \/><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Message *\" name=\"message\"><\/textarea><\/span>\n            <\/div>\n            <div class=\"input-group\">\n                <button type=\"submit\" class=\"button size-lg icon_right\">submit <i class=\"fa fa-chevron-right\"><\/i><\/button>\n            <\/div>\n        <\/div>\n    <\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-65dae21 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"65dae21\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-65db2a6\" data-id=\"65db2a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65db5ee elementor-widget elementor-widget-google_maps\" data-id=\"65db5ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=London%20Eye%2C%20London%2C%20United%20Kingdom&#038;t=m&#038;z=10&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"London Eye, London, United Kingdom\"\n\t\t\t\t\taria-label=\"London Eye, London, United Kingdom\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Please let us know if you have a question, want to leave a comment, or would like further information about Consulting WP. contact details 1010 Avenue of the Moon New York, NY 10018 US. +1 628 123 4000 br&#97;&#110;d&#111;n&#64;&#99;on&#115;ul&#116;&#105;n&#103;.c&#111;m Reason for Contact *Value1Value2 Area of Interest *Value1Value2 submit<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1476","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/pages\/1476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/comments?post=1476"}],"version-history":[{"count":1,"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/pages\/1476\/revisions"}],"predecessor-version":[{"id":7446,"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/pages\/1476\/revisions\/7446"}],"wp:attachment":[{"href":"https:\/\/instantcredit24.ro\/index.php\/wp-json\/wp\/v2\/media?parent=1476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}